{"id":5301,"date":"2024-04-10T07:09:25","date_gmt":"2024-04-10T07:09:25","guid":{"rendered":"https:\/\/serelda.daliisolutions.com\/index.php\/2024\/04\/10\/la-guardia-civil-de-novelda-y-aspe-participa-en-la-detencion-del-presunto-autor-de-material-deportivo-de-formula-kite\/"},"modified":"2024-04-10T07:09:25","modified_gmt":"2024-04-10T07:09:25","slug":"la-guardia-civil-de-novelda-y-aspe-participa-en-la-detencion-del-presunto-autor-de-material-deportivo-de-formula-kite","status":"publish","type":"post","link":"https:\/\/serelda.daliisolutions.com\/index.php\/2024\/04\/10\/la-guardia-civil-de-novelda-y-aspe-participa-en-la-detencion-del-presunto-autor-de-material-deportivo-de-formula-kite\/","title":{"rendered":"La Guardia Civil de Novelda y Aspe participa en la detenci\u00f3n del presunto autor de material deportivo de Formula Kite"},"content":{"rendered":"  <p><p><strong>Sigue el canal de la SER en WhatsApp<\/strong><br \/>Encontrar\u00e1s toda la informaci\u00f3n, el deporte y el entretenimiento: la actualidad del d\u00eda y las noticias de \u00faltima hora, los mejores v\u00eddeos y momentos de la radio, entrevistas, reportajes y mucho m\u00e1s.<\/p><a href=\"https:\/\/www.whatsapp.com\/channel\/0029Va633PF9WtC4l7XUzh1e\" title=\"Suscr\u00edbete\">Suscr\u00edbete ahora<\/a><\/p>   <p>Elda<\/p>   <p>La <b>Guardia Civil<\/b> ha llevado a cabo la detenci\u00f3n de <b>un hombre de 35 a\u00f1o<\/b>s como presunto autor de la <b>sustracci\u00f3n <\/b>de gran cantidad de <b>material deportivo de Formula Kite<\/b>, valorado en <b>450.000 euros,<\/b> en las instalaciones del Campeonato de Europa de F\u00f3rmula Kite en Los Alc\u00e1zares (Murcia). En menos de 24 horas desde que la Guardia Civil tuvo constancia del suceso, <b>se detuvo al presunto autor y se recuper\u00f3 el material<\/b>.<\/p>   <p>Los hechos sucedieron en la madrugada del s\u00e1bado 23 al domingo 24 de marzo en Los Alc\u00e1zares (Murcia), momento en el que se estaba celebrando el Campeonato de Europa de F\u00f3rmula Kite, en el que confluyeron deportistas reconocidos de esta modalidad, que iban acompa\u00f1ados del costoso material con el que realizan las pruebas.<\/p>   <p>El delincuente, haci\u00e9ndose pasar por un trabajador del evento y, usando como elemento de distracci\u00f3n un concierto de m\u00fasica, accedi\u00f3 a las instalaciones en las que se encontraba guardado el material deportivo de los participantes y lo carg\u00f3 en una furgoneta, march\u00e1ndose antes de ser sorprendido.<\/p>   <p>La ma\u00f1ana del d\u00eda 24, los afectados se percataron de la falta del material deportivo, valorado en unos 450.000 euros, dando la voz de alarma a los responsables del evento e informando a la patrulla del Servicio Mar\u00edtimo Provincial de la Guardia Civil de Murcia, que se encontraba en el lugar realizando labores de protecci\u00f3n y seguridad.<\/p>   <p>Inmediatamente, los agentes comenzaron las labores de investigaci\u00f3n, fruto de las cuales, lograron ubicar el material en un pol\u00edgono de Agost. Debido a esto, informaron a la Central Operativa de Servicios (COS) de la Guardia Civil de Murcia, que se coordin\u00f3 con el COS de Alicante, quienes remitieron las indicaciones a las Patrullas de la Guardia Civil de Novelda y Aspe, que se trasladaron al lugar, realizaron la b\u00fasqueda por la zona y localizaron la furgoneta.<\/p>   <p>Una vez realizadas identificado el sospechoso, los agentes procedieron a la apertura de la furgoneta, descubriendo en su interior todo el material deportivo sustra\u00eddo, m\u00e1s de 60 elementos, principalmente velas, cometas y tablas, adem\u00e1s de neoprenos y chalecos, procediendo a la detenci\u00f3n del presunto autor, un hombre de 35 a\u00f1os y nacionalidad francesa. La actuaci\u00f3n se resolvi\u00f3 en menos de 24 horas.<\/p>   <p>El d\u00eda 25 de marzo, el detenido, al que se le imputa el delito de hurto, fue puesto a disposici\u00f3n del Juzgado de Instrucci\u00f3n n\u00ba 2 de Novelda (Alicante), que ha decretado su puesta en libertad con la imposici\u00f3n de medidas cautelares.<\/p>   <p>Finalmente, la Guardia Civil contact\u00f3 cit\u00f3 a los afectados en el Puesto Principal de Novelda (Alicante), d\u00f3nde se les entreg\u00f3 su material.<\/p>   <p>Los afectados eran los finalistas de la competici\u00f3n. Actualmente, los competidores de esta disciplina se encuentran en la temporada previa de torneos que suman puntos para los Juegos Ol\u00edmpicos de Par\u00eds 2024, y el haber podido recuperar sus efectos les va a permitir continuar su recorrido de competiciones de Formula Kite sin perder puestos. Gracias a esta r\u00e1pida actuaci\u00f3n pudieron competir en el campeonato de Palma de Mallorca 2024, celebrado recientemente, entre el 28 de marzo y el 6 de abril.<\/p> ","protected":false},"excerpt":{"rendered":"<p>Los hechos sucedieron en la madrugada del s\u00e1bado 23 al domingo 24 de marzo en Los Alc\u00e1zares (Murcia), momento en el que se estaba celebrando el Campeonato de Europa de F\u00f3rmula Kite<\/p>\n","protected":false},"author":0,"featured_media":5302,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-de-ser-elda"],"acf":{"ser_id":"3XMQH27Q25ES7NVX45OFHKQVH4","ser_url":"https:\/\/cadenaser.com\/comunitat-valenciana\/2024\/04\/10\/la-guardia-civil-de-novelda-y-aspe-participa-en-la-detencion-del-presunto-autor-de-material-deportivo-de-formula-kite-radio-elda\/"},"_links":{"self":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts\/5301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/comments?post=5301"}],"version-history":[{"count":0,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts\/5301\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/media\/5302"}],"wp:attachment":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/media?parent=5301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/categories?post=5301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/tags?post=5301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}