{"id":5194,"date":"2024-04-07T09:30:01","date_gmt":"2024-04-07T09:30:01","guid":{"rendered":"https:\/\/serelda.daliisolutions.com\/index.php\/2024\/04\/07\/paqui-tarraga-tomas-c-a-elda-bronce-en-el-campeonato-de-espana-de-10k-ruta\/"},"modified":"2024-04-07T09:30:01","modified_gmt":"2024-04-07T09:30:01","slug":"paqui-tarraga-tomas-c-a-elda-bronce-en-el-campeonato-de-espana-de-10k-ruta","status":"publish","type":"post","link":"https:\/\/serelda.daliisolutions.com\/index.php\/2024\/04\/07\/paqui-tarraga-tomas-c-a-elda-bronce-en-el-campeonato-de-espana-de-10k-ruta\/","title":{"rendered":"Paqui T\u00e1rraga Tom\u00e1s (C. A. Elda), bronce en el Campeonato de Espa\u00f1a de 10K ruta"},"content":{"rendered":"  <p>Elda<\/p>   <p>La almanse\u00f1a, eldense de adopci\u00f3n, <b>Paqui T\u00e1rraga Tom\u00e1s<\/b>, atleta del <a href=\"https:\/\/www.facebook.com\/clubatletismoelda\/?locale=es_ES\" rel=\"nofollow noopener\" target=\"_blank\"><b>Club Atletismo Elda<\/b><\/a>, se ha colgado el <b>bronce<\/b> de la categor\u00eda F60 en el <a href=\"https:\/\/atletismorfea.es\/\" rel=\"nofollow noopener\" target=\"_blank\"><b>Campeonato de Espa\u00f1a de 10 km ruta <\/b><\/a>absoluto y m\u00e1ster<b> <\/b>disputado este s\u00e1bado en la localidad alicantina de Crevillente organizado por el C. A. Marathon Crevillent.<\/p>   <p>Paqui T\u00e1rraga invirti\u00f3 49\u00b4 04&#8243; en cubrir los 10.000 m del trazado por detr\u00e1s de M\u00aa Jos\u00e9 Hidalgo Quiles del Juventud Atl\u00e9tica Elche que acab\u00f3 segunda con un crono de 49\u00b4 04&#8243; y de Ana Isabel Arias Matas del C. D. Velociraptor de Guadalajara que se colg\u00f3 el oro con 48\u00b4 15&#8243;<\/p>   <p>Al finalizar la prueba, la atleta del C. A. Elda reconoc\u00eda que hizo \u00abun d\u00eda perfecto para correr\u00bb aunque no dejaba de se\u00f1alar que \u00abfue un circuito rompe piernas con muchos toboganes\u00bb lo que le da m\u00e1s brillo si cabe a su medalla de bronce en este Nacional.<\/p>   <p>Sigue el <a href=\"https:\/\/www.whatsapp.com\/channel\/0029Va633PF9WtC4l7XUzh1e\" rel=\"nofollow noopener\" target=\"_blank\">canal de La SER en WhatsApp<\/a>, donde encontrar\u00e1s toda la informaci\u00f3n, el deporte y el entretenimiento: la actualidad del d\u00eda y las noticias de \u00faltima hora, los mejores v\u00eddeos y momentos de la radio, entrevistas, reportajes y mucho m\u00e1s.<\/p> ","protected":false},"excerpt":{"rendered":"<p>La prueba se disput\u00f3 este s\u00e1bado en Crevillente<\/p>\n","protected":false},"author":0,"featured_media":5195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-5194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":{"ser_id":"IP4A5FUBIFEOFCRRHRNPGPQCTA","ser_url":"https:\/\/cadenaser.com\/comunitat-valenciana\/2024\/04\/07\/paqui-tarraga-tomas-c-a-elda-bronce-en-el-campeonato-de-espana-de-10k-ruta-radio-elda\/"},"_links":{"self":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts\/5194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/comments?post=5194"}],"version-history":[{"count":0,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts\/5194\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/media\/5195"}],"wp:attachment":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/media?parent=5194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/categories?post=5194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/tags?post=5194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}