{"id":17343,"date":"2025-02-14T12:56:01","date_gmt":"2025-02-14T12:56:01","guid":{"rendered":"https:\/\/serelda.daliisolutions.com\/index.php\/2025\/02\/14\/jose-luis-oltra-entrenador-del-eldense-el-partido-contra-el-depor-no-es-una-final-pero-vamos-a-jugar-como-si-lo-fuera\/"},"modified":"2025-02-14T12:56:01","modified_gmt":"2025-02-14T12:56:01","slug":"jose-luis-oltra-entrenador-del-eldense-el-partido-contra-el-depor-no-es-una-final-pero-vamos-a-jugar-como-si-lo-fuera","status":"publish","type":"post","link":"https:\/\/serelda.daliisolutions.com\/index.php\/2025\/02\/14\/jose-luis-oltra-entrenador-del-eldense-el-partido-contra-el-depor-no-es-una-final-pero-vamos-a-jugar-como-si-lo-fuera\/","title":{"rendered":"Jos\u00e9 Luis Oltra, entrenador del Eldense: \u201cEl partido contra el Depor no es una final, pero vamos a jugar como si lo fuera\u201d"},"content":{"rendered":"  <p><div data-adtype=\"MLDB\"><\/div><\/p>   <p>Elda<\/p>   <p>Jos\u00e9 Luis Oltra, entrenador del Eldense, ha comparecido este viernes en la sala de prensa del Nuevo Pepico Amat de Elda, antes de recibir el domingo (16.15 h) al R. C. Deportivo en el partido de la 27\u00aa jornada de LaLiga Hypermotion.<\/p> ","protected":false},"excerpt":{"rendered":"<p>El t\u00e9cnico azulgrana reconoce que la importancia del partido \u201ccontra un equipo al alza\u201d<\/p>\n","protected":false},"author":0,"featured_media":17344,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-17343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":{"ser_id":"V27EPY4465HNXEN7ZUF42NBIHI","ser_url":"https:\/\/cadenaser.com\/comunitat-valenciana\/2025\/02\/14\/jose-luis-oltra-entrenador-del-eldense-el-partido-contra-el-depor-no-es-una-final-pero-vamos-a-jugar-como-si-lo-fuera-radio-elda\/"},"_links":{"self":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts\/17343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/comments?post=17343"}],"version-history":[{"count":0,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts\/17343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/media\/17344"}],"wp:attachment":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/media?parent=17343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/categories?post=17343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/tags?post=17343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}