{"id":17297,"date":"2025-02-13T13:07:02","date_gmt":"2025-02-13T13:07:02","guid":{"rendered":"https:\/\/serelda.daliisolutions.com\/index.php\/2025\/02\/13\/carles-esteve-diputado-de-compromis-en-las-cortes-valencianas-la-sanidad-esta-mal-hay-mas-hospitales-privados-que-publicos\/"},"modified":"2025-02-13T13:07:02","modified_gmt":"2025-02-13T13:07:02","slug":"carles-esteve-diputado-de-compromis-en-las-cortes-valencianas-la-sanidad-esta-mal-hay-mas-hospitales-privados-que-publicos","status":"publish","type":"post","link":"https:\/\/serelda.daliisolutions.com\/index.php\/2025\/02\/13\/carles-esteve-diputado-de-compromis-en-las-cortes-valencianas-la-sanidad-esta-mal-hay-mas-hospitales-privados-que-publicos\/","title":{"rendered":"Carles Esteve, diputado de Comprom\u00eds en las Cortes Valencianas: \u201cLa sanidad est\u00e1 mal, hay m\u00e1s hospitales privados que p\u00fablicos\u201d"},"content":{"rendered":"  <p><div data-adtype=\"MLDB\"><\/div><\/p>   <p>Elda<\/p>   <p>Este jueves se debatir\u00e1 en el Centro C\u00edvico y Juvenil de Elda sobre la situaci\u00f3n de la sanidad p\u00fablica. Ser\u00e1 a partir de las 19.00 h en una mesa redonda que contar\u00e1 con la presencia de Carles Esteve, portavoz de Sanidad de Comprom\u00eds en las Cortes Valencianos.<\/p>   <p>En Hoy por Hoy Elda Vinalop\u00f3 ha denunciado el mal momento que atraviesa poniendo el foco en que \u00abcon los datos del \u00faltimo a\u00f1o, tenemos la mala noticia de que las listas de espera vuelven a aumentar. Si antes tard\u00e1bamos 70 d\u00edas en entrevistar a un ni\u00f1o o una ni\u00f1a, ahora tardamos 150, es inasumible\u00bb.<\/p>   <p>Adem\u00e1s, ha lamentado que \u00abes la primera vez que en la Comunidad Valenciana hay m\u00e1s hospitales privados que p\u00fablicos\u00bb. Por todo ello, Esteve ha animado a la ciudadan\u00eda a acudir al Centro C\u00edvico y Juvenil para presenciar este debate y ser part\u00edcipe de uno de los problemas que m\u00e1s afecta actualmente a la poblaci\u00f3n.<\/p>   <p>Ha expresado que \u00abvolvemos a estar en un momento en el que queremos hablar de lo que nos pasa, y lo que nos pasa es que vamos al centro de salud y tardan muchos d\u00edas en atendernos. Pero esto tiene soluci\u00f3n, y la soluci\u00f3n pasa por reunirnos todos y plantearla\u00bb.<\/p> ","protected":false},"excerpt":{"rendered":"<p>El portavoz de Sanidad de Comprom\u00eds ha repasado en Hoy por Hoy Elda Vinalop\u00f3 la actualidad del \u00e1rea<\/p>\n","protected":false},"author":0,"featured_media":17298,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app-de-ser-elda"],"acf":{"ser_id":"VI2N6PODLVHQDEJ7FFG3VWNK64","ser_url":"https:\/\/cadenaser.com\/comunitat-valenciana\/2025\/02\/13\/carles-esteve-diputado-de-compromis-en-las-cortes-valencianas-la-sanidad-esta-mal-hay-mas-hospitales-privados-que-publicos-radio-elda\/"},"_links":{"self":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts\/17297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/comments?post=17297"}],"version-history":[{"count":0,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts\/17297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/media\/17298"}],"wp:attachment":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/media?parent=17297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/categories?post=17297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/tags?post=17297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}