{"id":16083,"date":"2025-01-17T08:10:48","date_gmt":"2025-01-17T08:10:48","guid":{"rendered":"https:\/\/serelda.daliisolutions.com\/index.php\/2025\/01\/17\/el-capet-petrer-firma-una-sobresaliente-actuacion-en-el-provincial-absoluto-por-equipos-de-elche\/"},"modified":"2025-01-17T08:10:48","modified_gmt":"2025-01-17T08:10:48","slug":"el-capet-petrer-firma-una-sobresaliente-actuacion-en-el-provincial-absoluto-por-equipos-de-elche","status":"publish","type":"post","link":"https:\/\/serelda.daliisolutions.com\/index.php\/2025\/01\/17\/el-capet-petrer-firma-una-sobresaliente-actuacion-en-el-provincial-absoluto-por-equipos-de-elche\/","title":{"rendered":"El CAPET Petrer firma una sobresaliente actuaci\u00f3n en el Provincial Absoluto por equipos de Elche"},"content":{"rendered":"  <p><div data-adtype=\"MLDB\"><\/div><\/p>   <p>Elda<\/p>   <p>El pasado viernes, en las instalaciones de Caixapetrer, se celebraba la gala de presentaci\u00f3n de la temporada 2025 del CAPET donde los m\u00e1s de 180 componentes desde los m\u00e1s peque\u00f1os hasta los masters, as\u00ed como colaboradores y amigos celebraron los logros conseguidos la pasada temporada, objetivos para el 2025 y lo m\u00e1s importante, el compromiso social del club hacia todos sus componentes creando una gran familia como es el CAPET.<\/p>  <p><figure><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cadenaser.com\/resizer\/v2\/KPLTR35OXZFI5CLJLOQZPJJGDM.jpg?auth=e27fe705ffd795986b49d599c14eebc5a5764f549b82d0d3a32be24523613d87&amp;quality=70&amp;width=650&amp;height=322&amp;smart=true\" alt=\"Presentaci\u00f3n de los equipos del CAPET Petrer\" width=\"650\" height=\"323\" \/><figcaption class=\"fc\"><p><span>Presentaci\u00f3n de los equipos del CAPET Petrer<\/span> \/ <span>Capet<\/span><\/p><\/figcaption><\/figure><button class=\"bt-am\">Ampliar<\/button><div class=\"lb d-none\"><div><figure><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cadenaser.com\/resizer\/v2\/KPLTR35OXZFI5CLJLOQZPJJGDM.jpg?auth=e27fe705ffd795986b49d599c14eebc5a5764f549b82d0d3a32be24523613d87\" alt=\"Presentaci\u00f3n de los equipos del CAPET Petrer\" width=\"650\" height=\"323\" \/><figcaption class=\"fc\"><p><span>Presentaci\u00f3n de los equipos del CAPET Petrer<\/span> \/ <span>Capet<\/span><\/p><\/figcaption><\/figure><button>Cerrar<\/button><\/div><\/div><\/p>   <p>Campeonato Provincial Absoluto por equipos<\/p>   <p>Ya el s\u00e1bado por la tarde, en las instalaciones Manolo Ja\u00e9n de Elche se disputaba el Campeonato Provincial Absoluto por Equipos Short Track donde las componentes del equipo femenino se hac\u00edan con la victoria dos puntos por delante que el Elche Decathlon, club anfitri\u00f3n, siendo la primera vez que un club comarcal consigue este trofeo en categor\u00eda absoluta.<\/p>   <p>Adem\u00e1s, el equipo masculino, tambi\u00e9n firmaba una excelente actuaci\u00f3n alz\u00e1ndose a la tercera posici\u00f3n del p\u00f3dium.<\/p>   <p>Gracias a estos resultados y a las marcas anteriores, ha permitido al Club Atletismo Petrer CAPET clasificar a ambos equipos, en el Campeonato Auton\u00f3mico que se celebra este s\u00e1bado 18 en el Vel\u00f3dromo Luis Puig de Valencia<\/p>   <p>A destacar tambi\u00e9n la juventud de ambos equipos donde la media rondaba los 18 a\u00f1os, demostrando el futuro que el club tiene por delante y lo importante que es formar atletas desde la base para seguir creciendo.<\/p>   <p>     .c-w{         max-width:444px;         width:100%;         margin:32px auto;      background:#00755E;         border-radius:4px;         display:flex;         align-items:center;         justify-content:center;     }     .c-w a{         display:flex;         align-items:center;         justify-content:center;         padding:4px 24px;     }     .c-w img{         width:24px;         margin-right:12px;     }     .c-w p{         font:18px\/25px Poppins;         text-align:center;         color:#fff;         margin:0;     }     @media (max-width:444px){         .c-w a{             padding:4px 12px;         }         .c-w img{             width:24px;             margin-right:8px;         }         .c-w p{             font:14px\/25px Poppins;         }     }     @media (max-width:335px){         .c-w p{             font:13px\/25px Poppins;         }     }  <div class=\"c-w\">     <a href=\"https:\/\/www.whatsapp.com\/channel\/0029Va633PF9WtC4l7XUzh1e\" rel=\"nofollow\" target=\"_blank\">         <img decoding=\"async\" src=\"https:\/\/cadenaser.com\/estaticos\/recursosgraficos\/responsive\/img\/ico-whatsapp.svg\" alt=\"Whatsapp\">         <p>\u00danete al <b>canal de WhatsApp<\/b> de la SER<\/p>     <\/a> <\/div><\/p>   <p>Cross Ciudad de Novelda<\/p>   <p>El domingo era en Novelda donde se celebraba el Cross Ciudad de Novelda con una amplia participaci\u00f3n del club destacando los p\u00f3diums de Virginia Armero, Encarni Bonal y Abel Ferris en categor\u00eda Master y, al ser clasificatorio para el Campeonato de Espa\u00f1a por federaciones auton\u00f3micas, Julia Nortes se hac\u00eda con una plaza en el equipo que representar\u00e1 a la Comunidad Valenciana en dicho campeonato a celebrar el pr\u00f3ximo d\u00eda 25 en la ciudad madrile\u00f1a de Getafe<\/p>   <p>Fin de semana<\/p>   <p>Este fin de semana tambi\u00e9n viene completo para el club empezando el s\u00e1bado por la ma\u00f1ana en Elche donde el equipo masculino Sub 14 disputar\u00e1 el Campeonato Provincial por Equipos de su categor\u00eda y por la tarde, como ya hemos comentado, ser\u00e1n los equipos femenino y masculino lo que participen en el Campeonato Auton\u00f3mico Absoluto por Equipos en la ciudad de Valencia.<\/p>   <p>Por otro lado, Julia Nortes, Sergio Callado y Juan Gabriel Armero estar\u00e1n con el FACSA-Playas de Castell\u00f3n en la ciudad de Zaragoza, donde se celebra el European DNA Meeting Clubes.<\/p> ","protected":false},"excerpt":{"rendered":"<p>Las f\u00e9minas se impon\u00edan con una ventaja de dos puntos, al Elche Decathlon<\/p>\n","protected":false},"author":0,"featured_media":16084,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-16083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":{"ser_id":"ORBEKYPQXBFL7M6IP6JGJGJADQ","ser_url":"https:\/\/cadenaser.com\/comunitat-valenciana\/2025\/01\/17\/el-capet-petrer-firma-una-sobresaliente-actuacion-en-el-provincial-absoluto-por-equipos-de-elche-radio-elda\/"},"_links":{"self":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts\/16083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/comments?post=16083"}],"version-history":[{"count":0,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/posts\/16083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/media\/16084"}],"wp:attachment":[{"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/media?parent=16083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/categories?post=16083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serelda.daliisolutions.com\/index.php\/wp-json\/wp\/v2\/tags?post=16083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}